{"id":10398,"date":"2024-05-16T17:46:02","date_gmt":"2024-05-16T14:46:02","guid":{"rendered":"https:\/\/demo.artureanec.com\/themes\/neuros-dark\/?page_id=10398"},"modified":"2024-05-16T17:46:02","modified_gmt":"2024-05-16T14:46:02","slug":"home-6","status":"publish","type":"page","link":"https:\/\/nuvaleoai.co.uk\/staging\/home-6\/","title":{"rendered":"Home 6"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10398\" class=\"elementor elementor-10398\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e14f9a1 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"e14f9a1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-900c0cf\" data-id=\"900c0cf\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ffd0224 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffd0224\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-8eac0ad\" data-id=\"8eac0ad\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c26a8c9 elementor-widget elementor-widget-neuros_heading\" data-id=\"c26a8c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h1 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Discover the Smart AI Neuro <del>Chatbot<\/del><\/span><\/h1><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6094a6a blur-filter elementor-widget__width-initial wpforms-button-border-style-solid wpforms-button-bakground-style-solid elementor-widget elementor-widget-neuros_wpforms\" data-id=\"6094a6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros-wpforms-widget\">\n            <style id=\"wpforms-css-vars-24126\">\n\t\t\t\t#wpforms-24126 {\n\t\t\t\t\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-11467\"><form id=\"wpforms-form-24126\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"24126\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/staging\/wp-json\/wp\/v2\/pages\/10398\" data-token=\"4434f048fae06e9c1f817bc9c7df08c5\" data-token-time=\"1778680456\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-11467-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label wpforms-label-hide\" for=\"wpforms-11467-field_2\" aria-hidden=\"false\">Email <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-11467-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" placeholder=\"Enter your email\" spellcheck=\"false\" aria-errormessage=\"wpforms-11467-field_2-error\" required><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"11467\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/pages\/10398\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-11467\" class=\"wpforms-submit hide\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d7b3b8 neuros-button-border-style-solid elementor-widget__width-auto neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_button\" data-id=\"8d7b3b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"button-widget\">\n            <div class=\"button-container\">\n                                <a class=\"neuros-button\" href=\"#\" href=\"#\" target=\"_blank\">Try Chatbot Neuro for free                        <span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span>                    \n                    <span class=\"button-inner\"><\/span>\n                <\/a>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-742b712 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"742b712\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f67ba3 elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2f67ba3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Free 14-day trial<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-check-circle\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">No credit card required<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0733d2 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"d0733d2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"116\" height=\"116\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-46.png\" class=\"attachment-large size-large wp-image-10430\" alt=\"\" srcset=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-46.png 116w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-46-100x100.png 100w\" sizes=\"(max-width: 116px) 100vw, 116px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dcc8be elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"1dcc8be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"116\" height=\"116\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-45.png\" class=\"attachment-large size-large wp-image-10429\" alt=\"\" srcset=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-45.png 116w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Ellipse-45-100x100.png 100w\" sizes=\"(max-width: 116px) 100vw, 116px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00bfdc1 elementor-shape-square e-grid-align-left elementor-widget__width-auto elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"00bfdc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-icon-star-filled elementor-repeater-item-64ac01d\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Icon-star-filled<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-star-filled\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-icon-star-filled elementor-repeater-item-884bb5b\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Icon-star-filled<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-star-filled\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-icon-star-filled elementor-repeater-item-4881f7e\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Icon-star-filled<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-star-filled\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-icon-star-filled elementor-repeater-item-e148c1c\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Icon-star-filled<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-star-filled\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-icon-star-filled elementor-repeater-item-6c8b8fe\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Icon-star-filled<\/span>\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fontello icon-star-filled\"><\/i>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-267a59b elementor-widget__width-auto elementor-widget elementor-widget-text-editor\" data-id=\"267a59b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>20K+ users<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-aa3343a\" data-id=\"aa3343a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5fac524 elementor-widget__width-auto elementor-absolute elementor-widget elementor-widget-image\" data-id=\"5fac524\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"297\" height=\"249\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Bubbles.png\" class=\"attachment-full size-full wp-image-11513\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-c6958ae elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"c6958ae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-3bd27a4\" data-id=\"3bd27a4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7902b6d neuros-video-button-alignment-right neuros-video-button-decoration-on elementor-widget elementor-widget-neuros_video_button\" data-id=\"7902b6d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XHOmBV4js_E&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"neuros_video_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros_video_button_container\">\n            <div class=\"neuros_video_button_widget\">\n                                        <div class=\"elementor-wrapper elementor-open-lightbox\">\n                                                        <div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/XHOmBV4js_E?feature=oembed&amp;wmode=opaque&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-7902b6d&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n                                <div class=\"elementor-custom-embed-play\" role=\"button\">\n                                                                                <div class=\"icon-play-wrapper\">\n                                                <i class=\"eicon-play\" aria-hidden=\"true\"><\/i>\n                                            <\/div>\n                                                                            \n                                                                                <span class=\"neuros_button_text\">Watch video<\/span>\n                                                                                <span class=\"elementor-screen-only\">Watch video<\/span>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-844bba9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"844bba9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-64da6c8\" data-id=\"64da6c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d9dfb title-alignment-center elementor-widget elementor-widget-neuros_image_carousel\" data-id=\"38d9dfb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_image_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-image-slider-widget\">\n\n            \n            <div class=\"slider-wrapper\">\n                <div class=\"owl-carousel owl-theme view-type-1\" data-slider-options={&quot;items&quot;:6,&quot;nav&quot;:false,&quot;dots&quot;:true,&quot;dotsContainer&quot;:&quot;.owl-dots-38d9dfb&quot;,&quot;dotsContainerMobile&quot;:&quot;.owl-dots-38d9dfb&quot;,&quot;autoplayHoverPause&quot;:true,&quot;autoplay&quot;:false,&quot;autoplaySpeed&quot;:300,&quot;autoplayTimeout&quot;:5000,&quot;loop&quot;:true,&quot;speed&quot;:500}>\n                    <div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"170\" height=\"53\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_1.png\" class=\"attachment-full size-full wp-image-1120\" alt=\"\" \/><\/div><\/div><div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"162\" height=\"60\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_2.png\" class=\"attachment-full size-full wp-image-1121\" alt=\"\" \/><\/div><\/div><div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"131\" height=\"72\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_3.png\" class=\"attachment-full size-full wp-image-1122\" alt=\"\" \/><\/div><\/div><div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"183\" height=\"44\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_4.png\" class=\"attachment-full size-full wp-image-1123\" alt=\"\" \/><\/div><\/div><div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"53\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_5.png\" class=\"attachment-full size-full wp-image-1124\" alt=\"\" \/><\/div><\/div><div class=\"slider-item\"><div class=\"slider-item-inner\"><img loading=\"lazy\" decoding=\"async\" width=\"104\" height=\"92\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/01\/partners_6.png\" class=\"attachment-full size-full wp-image-1125\" alt=\"\" \/><\/div><\/div>                <\/div>\n            <\/div>\n\n            <div class=\"owl-dots owl-dots-38d9dfb\"><\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1ac50ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1ac50ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-extended\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-e4d4715\" data-id=\"e4d4715\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-46229d6 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"46229d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h3 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Neuro Intelligent Chatbot Platform<\/span><\/h3><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea386a5 elementor-widget elementor-widget-image\" data-id=\"ea386a5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"447\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Dashboard-min.jpg\" class=\"attachment-large size-large wp-image-10520\" alt=\"\" srcset=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Dashboard-min.jpg 778w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Dashboard-min-600x345.jpg 600w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Dashboard-min-300x172.jpg 300w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/05\/Dashboard-min-768x441.jpg 768w\" sizes=\"(max-width: 778px) 100vw, 778px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a9c2a7b\" data-id=\"a9c2a7b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ea984a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ea984a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-911dc0b\" data-id=\"911dc0b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fc450bb elementor-widget elementor-widget-neuros_heading\" data-id=\"fc450bb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h5 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">AI Integration and Deployment<\/span><\/h5><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce6dc46 elementor-widget elementor-widget-text-editor\" data-id=\"ce6dc46\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Assist in seamlessly integrating AI solutions into your existing systems and deploying them at scale.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-101729e elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"101729e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"98\" height=\"100\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/02\/Messenger-Logo-1.png\" class=\"attachment-large size-large wp-image-3709\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c846b9c elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"c846b9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"88\" height=\"90\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/02\/skype-logo-vector-icon-template-clipart-download-0-1.png\" class=\"attachment-large size-large wp-image-3710\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-67633b2 elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"67633b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"102\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/02\/Telegram-Symbol-1.png\" class=\"attachment-large size-large wp-image-3711\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d885ecd elementor-widget__width-auto elementor-widget elementor-widget-image\" data-id=\"d885ecd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"#\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"102\" height=\"104\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/02\/discord-1.png\" class=\"attachment-large size-large wp-image-3712\" alt=\"\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca6e197 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ca6e197\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d2a53be\" data-id=\"d2a53be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a127277 elementor-widget elementor-widget-neuros_special_text\" data-id=\"a127277\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_special_text.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"special-text-wrapper animate animated animation-direction-left\"><div class=\"special-text\">\/ Artificial Intellegance in shaping the future of technology.&nbsp;<\/div><div class=\"special-text\">\/ Artificial Intellegance in shaping the future of technology.&nbsp;<\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f8c850d elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f8c850d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1447666\" data-id=\"1447666\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b59ce67 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b59ce67\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d1b3f3f\" data-id=\"d1b3f3f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37baf6a elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"37baf6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">features<\/span><span class=\"neuros-heading-content has_gradient_color_text\">The unique selling points &amp; advantages of our service<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-24074b8\" data-id=\"24074b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-219acc6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"219acc6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2c26105\" data-id=\"2c26105\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c0914d9 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"c0914d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 27 23\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M26.5345 0.793091H0.465517C0.208552 0.793091 0 1.00118 0 1.25861V21.7414C0 21.9988 0.208552 22.2069 0.465517 22.2069H26.5345C26.7914 22.2069 27 21.9988 27 21.7414V1.25861C27 1.00118 26.7914 0.793091 26.5345 0.793091ZM26.069 21.2759H0.931035V1.72413H26.069V21.2759Z\"\/>\n<path d=\"M7.44793 11.0986C8.87754 11.0986 10.0404 9.93577 10.0404 8.50663C10.0404 7.07656 8.87754 5.9137 7.44793 5.9137C6.01833 5.9137 4.85547 7.07656 4.85547 8.50616C4.85547 9.93577 6.01833 11.0986 7.44793 11.0986ZM7.44793 6.84473C8.36407 6.84473 9.10937 7.59049 9.10937 8.50616C9.10937 9.42183 8.36407 10.1676 7.44793 10.1676C6.5318 10.1676 5.7865 9.4223 5.7865 8.50663C5.7865 7.59095 6.5318 6.84473 7.44793 6.84473Z\"\/>\n<path d=\"M3.25873 19.4138C3.36766 19.4138 3.47753 19.3757 3.56597 19.2979L11.16 12.6122L15.9557 17.4075C16.1377 17.5895 16.4319 17.5895 16.614 17.4075C16.796 17.2254 16.796 16.9312 16.614 16.7492L14.3762 14.5115L18.6501 9.83117L23.8923 14.6367C24.0818 14.8103 24.3765 14.7973 24.5501 14.6078C24.7237 14.4184 24.7112 14.1237 24.5212 13.9501L18.935 8.82937C18.8438 8.74605 18.7223 8.70461 18.5999 8.70741C18.4765 8.71299 18.3601 8.76746 18.2768 8.8587L13.7175 13.8523L11.5096 11.6444C11.3355 11.4707 11.0571 11.4619 10.8727 11.6239L2.95103 18.5987C2.75784 18.7686 2.73922 19.0628 2.90913 19.256C3.0013 19.3608 3.12978 19.4138 3.25873 19.4138Z\"\/>\n<\/svg><\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Image synthesis<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI image generators can synthesize new, unique images from scratch and providing best silutions.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-b12f68b\" data-id=\"b12f68b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-661c902 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"661c902\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 33 29\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M32.923 8.30336C32.924 8.30168 32.9253 8.30032 32.9263 8.29864C32.9284 8.29522 32.9301 8.29167 32.9321 8.28818C32.9372 8.27972 32.942 8.27119 32.9465 8.26241C32.9495 8.25654 32.9523 8.25059 32.955 8.24465C32.9589 8.23632 32.9625 8.22793 32.9659 8.2194C32.9686 8.21262 32.9711 8.20578 32.9734 8.19893C32.976 8.19112 32.9786 8.1833 32.9809 8.17529C32.9831 8.16742 32.9851 8.15954 32.987 8.1516C32.9886 8.14443 32.9902 8.13719 32.9915 8.1299C32.9932 8.12098 32.9945 8.11214 32.9956 8.10322C32.9964 8.09657 32.9973 8.08986 32.9978 8.08308C32.9986 8.07345 32.999 8.06383 32.9993 8.05421C32.9994 8.05008 32.9999 8.04607 32.9999 8.04194C32.9999 8.03948 32.9996 8.03703 32.9995 8.03458C32.9994 8.02547 32.9988 8.01637 32.9982 8.00726C32.9977 7.9999 32.9972 7.99254 32.9963 7.98524C32.9954 7.97775 32.9941 7.97032 32.9929 7.96289C32.9915 7.95437 32.9901 7.94578 32.9883 7.93745C32.987 7.93138 32.9852 7.92537 32.9837 7.91937C32.9812 7.91007 32.9788 7.90077 32.9759 7.89173C32.9741 7.88617 32.9719 7.88075 32.9699 7.87526C32.9665 7.86615 32.9633 7.85711 32.9594 7.84827C32.9568 7.84213 32.9537 7.83625 32.9507 7.83025C32.9469 7.8225 32.9433 7.81468 32.9391 7.80713C32.9351 7.7999 32.9306 7.79299 32.9263 7.78595C32.9225 7.77994 32.919 7.77387 32.915 7.76812C32.9097 7.76044 32.9038 7.75301 32.8981 7.74558C32.8943 7.74074 32.8908 7.73583 32.8869 7.73112C32.8809 7.72395 32.8744 7.71717 32.8679 7.71032C32.8635 7.70567 32.8593 7.7009 32.8547 7.69638C32.8487 7.6905 32.8423 7.68495 32.836 7.67933C32.8302 7.67416 32.8243 7.66899 32.8183 7.66415C32.8127 7.65969 32.8069 7.65556 32.8012 7.65136C32.7936 7.64581 32.786 7.64045 32.7782 7.63535C32.7762 7.63406 32.7744 7.63251 32.7723 7.63128L28.6392 5.04811C28.6364 5.04637 28.6335 5.04501 28.6306 5.04333C28.6249 5.03991 28.6193 5.03642 28.6134 5.03326C28.6098 5.03132 28.6062 5.02951 28.6025 5.0277C28.5967 5.02473 28.5909 5.02202 28.5849 5.01931C28.5802 5.01711 28.5755 5.01485 28.5707 5.01278C28.5673 5.01136 28.564 5.01014 28.5606 5.00884C28.5527 5.00575 28.5449 5.0029 28.5369 5.00026C28.534 4.99929 28.5313 4.998 28.5283 4.99709C28.5274 4.99683 28.5265 4.99664 28.5257 4.99638C28.5229 4.99554 28.52 4.99483 28.5172 4.99399C28.5079 4.99128 28.4987 4.98902 28.4894 4.98689C28.4858 4.98611 28.4824 4.98502 28.4788 4.9843C28.4765 4.98385 28.4742 4.98366 28.4718 4.98321C28.4624 4.98146 28.453 4.98004 28.4435 4.97882C28.4367 4.97798 28.4299 4.97714 28.4231 4.97656C28.4147 4.97584 28.4065 4.97546 28.3981 4.9752C28.3902 4.97494 28.3823 4.97475 28.3744 4.97488C28.3671 4.97501 28.36 4.97539 28.3527 4.97584C28.3499 4.97604 28.3471 4.97604 28.3442 4.97623C28.3424 4.97636 28.3405 4.9763 28.3386 4.97649C28.3347 4.97688 28.3308 4.97759 28.3269 4.97804C28.3203 4.97882 28.3136 4.97985 28.307 4.98088C28.3048 4.9812 28.3026 4.98146 28.3004 4.98185C28.2975 4.98237 28.2945 4.98256 28.2916 4.98314C28.288 4.98385 28.2845 4.98489 28.2809 4.98566C28.2743 4.98708 28.2677 4.98883 28.261 4.9905C28.2528 4.99264 28.2446 4.99483 28.2365 4.99741C28.2294 4.99967 28.2224 5.00219 28.2155 5.00478C28.2103 5.00665 28.2051 5.00826 28.2 5.01033C28.1979 5.01117 28.1958 5.01233 28.1937 5.01324C28.1861 5.0164 28.1788 5.01995 28.1714 5.0235C28.1664 5.02596 28.1612 5.02822 28.1562 5.0308C28.1557 5.03106 28.1551 5.03125 28.1546 5.03158L20.756 8.9775L16.3582 3.60231C16.358 3.60205 16.3577 3.60186 16.3575 3.6016C16.3562 3.59992 16.3548 3.59831 16.3533 3.59663C16.3499 3.59256 16.3462 3.58888 16.3426 3.58494C16.3358 3.57732 16.3289 3.56963 16.3216 3.56246C16.3173 3.55827 16.3126 3.55446 16.3081 3.55045C16.3011 3.54406 16.2942 3.5376 16.2868 3.53159C16.2797 3.52598 16.2722 3.52087 16.2649 3.51558C16.2644 3.51519 16.2638 3.51474 16.2633 3.51435C16.2584 3.51093 16.2538 3.50718 16.2488 3.50389C16.2414 3.49898 16.2334 3.49472 16.2257 3.4902C16.2198 3.48678 16.214 3.4831 16.208 3.47993C16.2008 3.47612 16.1932 3.47296 16.1857 3.46953C16.1788 3.46637 16.172 3.46288 16.165 3.46004C16.1582 3.45733 16.1513 3.4552 16.1444 3.45281C16.1362 3.4499 16.128 3.44687 16.1197 3.44441C16.1187 3.44409 16.1176 3.44364 16.1166 3.44338C16.1092 3.44125 16.1019 3.43996 16.0945 3.43821C16.0879 3.43666 16.0813 3.43485 16.0745 3.43356C16.0716 3.43305 16.0689 3.4324 16.066 3.43188L1.60273 0.848908C1.59795 0.848068 1.59323 0.84781 1.58846 0.847099C1.57974 0.845808 1.57108 0.844581 1.56237 0.843741C1.55436 0.842966 1.54648 0.842579 1.53854 0.842256C1.53098 0.841933 1.52342 0.841675 1.51587 0.841675C1.50722 0.841675 1.49863 0.841998 1.49004 0.842514C1.48306 0.842902 1.47602 0.843419 1.46905 0.844064C1.4604 0.844904 1.45181 0.846066 1.44328 0.847422C1.43618 0.84852 1.42914 0.849747 1.4221 0.851103C1.41396 0.852718 1.40595 0.854591 1.39795 0.856657C1.39052 0.85853 1.38309 0.860597 1.37573 0.862857C1.36831 0.865117 1.36107 0.867571 1.35377 0.870219C1.34609 0.872996 1.33853 0.875902 1.33098 0.879066C1.324 0.881972 1.31722 0.885137 1.31038 0.888366C1.30302 0.891853 1.29572 0.895469 1.28849 0.899344C1.28145 0.903154 1.2746 0.907158 1.26782 0.911291C1.2613 0.915231 1.25477 0.919235 1.24838 0.923497C1.24089 0.928534 1.23366 0.93383 1.22649 0.939254C1.22274 0.942096 1.21874 0.94455 1.21506 0.94752C1.21332 0.948876 1.21189 0.950426 1.21015 0.951847C1.20292 0.957788 1.19601 0.964117 1.1891 0.970511C1.18413 0.975096 1.17902 0.979616 1.17424 0.984395C1.16805 0.990595 1.1623 0.997182 1.15642 1.0037C1.15158 1.00913 1.1466 1.01442 1.14208 1.01998C1.13692 1.02631 1.13214 1.03302 1.1273 1.03967C1.12277 1.04581 1.11813 1.05188 1.11393 1.05814C1.10954 1.0648 1.1056 1.07171 1.10153 1.07862C1.09752 1.08533 1.09339 1.09192 1.08977 1.09877C1.08616 1.10561 1.08299 1.11278 1.0797 1.11982C1.07628 1.12712 1.07273 1.13435 1.06969 1.14177C1.06685 1.14862 1.06452 1.15572 1.06201 1.16276C1.05916 1.17077 1.05619 1.17878 1.0538 1.18692C1.0518 1.19363 1.05019 1.20061 1.04844 1.20752C1.04625 1.2163 1.04405 1.22502 1.04237 1.23386C1.04192 1.23613 1.04121 1.23832 1.04082 1.24058C1.03992 1.24549 1.03966 1.25033 1.03895 1.25524C1.03772 1.26376 1.0365 1.27229 1.03572 1.28088C1.03495 1.28889 1.03456 1.29683 1.03424 1.30477C1.03391 1.31239 1.03366 1.32001 1.03366 1.32763C1.03366 1.33616 1.03404 1.34462 1.03449 1.35308C1.03488 1.36025 1.0354 1.36735 1.03611 1.37452C1.03695 1.38304 1.03811 1.39144 1.0394 1.39983C1.0405 1.40707 1.04179 1.4143 1.04321 1.42147C1.04483 1.42948 1.04664 1.43735 1.0487 1.44523C1.05064 1.45279 1.05271 1.46028 1.05497 1.46777C1.05723 1.47507 1.05968 1.4823 1.06226 1.48947C1.06504 1.49715 1.06795 1.50484 1.07111 1.5124C1.07402 1.51931 1.07712 1.52615 1.08035 1.53293C1.08383 1.54029 1.08745 1.54759 1.09132 1.55482C1.09507 1.56186 1.09914 1.56864 1.10321 1.57549C1.10715 1.58208 1.11115 1.5886 1.11548 1.59499C1.12045 1.60242 1.12575 1.60959 1.13111 1.61669C1.13395 1.6205 1.1364 1.6245 1.13944 1.62825L4.22968 5.49106H0.484344C0.479953 5.49106 0.475755 5.49158 0.471429 5.4917C0.462517 5.49196 0.453605 5.49235 0.444693 5.49306C0.436879 5.49371 0.429129 5.49461 0.421444 5.49558C0.413888 5.49655 0.406333 5.49771 0.398842 5.499C0.390317 5.50049 0.381922 5.5023 0.373591 5.50423C0.366875 5.50578 0.360223 5.50753 0.353571 5.5094C0.344982 5.51179 0.336587 5.51437 0.328192 5.51728C0.321669 5.51947 0.315211 5.52186 0.308753 5.52438C0.30081 5.52748 0.292996 5.53071 0.285311 5.5342C0.278466 5.5373 0.271685 5.54059 0.264969 5.54401C0.258059 5.54757 0.251213 5.55118 0.244497 5.55506C0.237329 5.55912 0.23029 5.56345 0.223315 5.56791C0.217309 5.57178 0.211432 5.57572 0.20562 5.57979C0.198517 5.58476 0.191607 5.58999 0.184761 5.59542C0.179207 5.59981 0.173847 5.60427 0.168552 5.60885C0.162159 5.6144 0.15583 5.62009 0.149695 5.62596C0.144076 5.63132 0.138716 5.63681 0.133356 5.64243C0.128061 5.64799 0.122894 5.65367 0.117857 5.65955C0.11198 5.66639 0.106362 5.67343 0.100873 5.6806C0.098225 5.68402 0.0953836 5.68706 0.0928004 5.69054C0.0913151 5.69261 0.0901526 5.69474 0.0887319 5.69681C0.0831781 5.70469 0.0780763 5.71276 0.0729746 5.7209C0.0695519 5.72645 0.066 5.732 0.0628356 5.73762C0.0583796 5.74557 0.0543112 5.7537 0.0502427 5.7619C0.0471429 5.76817 0.0439785 5.77443 0.041137 5.78076C0.0377789 5.78838 0.0348728 5.7962 0.0319022 5.80401C0.0291898 5.81118 0.0263483 5.81835 0.0239589 5.82564C0.021634 5.83281 0.0196967 5.84017 0.0176947 5.84754C0.0154344 5.85567 0.0131742 5.86381 0.0114305 5.87201C0.00994521 5.87879 0.00891194 5.8857 0.00768493 5.89255C0.00613503 5.90152 0.00458513 5.9105 0.00355186 5.91954C0.00277691 5.92606 0.00238943 5.93265 0.00193738 5.9393C0.00122701 5.9488 0.000645793 5.95835 0.000516634 5.96785C0.000322896 5.97037 0 5.97282 0 5.9754C0 5.97979 0.000516634 5.98399 0.000645793 5.98832C0.00090411 5.99723 0.00122701 6.00614 0.00200196 6.01505C0.00264775 6.02287 0.00355186 6.03055 0.00452055 6.0383C0.00548924 6.04592 0.00665166 6.05348 0.00800783 6.06097C0.00949315 6.06943 0.0113014 6.07783 0.0132387 6.08616C0.0148532 6.09294 0.0165323 6.09965 0.0184051 6.10631C0.0207945 6.11483 0.0233777 6.12316 0.0262192 6.13149C0.0284795 6.13814 0.0308689 6.14467 0.0334521 6.15119C0.0364873 6.159 0.0397162 6.16675 0.0431389 6.17437C0.0463033 6.18135 0.0496615 6.18826 0.0530841 6.1951C0.0565714 6.20188 0.0601233 6.2086 0.0638689 6.21519C0.068002 6.22248 0.0724579 6.22965 0.0769785 6.23675C0.0807241 6.24263 0.0845988 6.24844 0.0886027 6.25413C0.0936399 6.2613 0.0989354 6.26833 0.104425 6.27524C0.108751 6.28067 0.113143 6.28603 0.117663 6.29126C0.123217 6.29772 0.128965 6.30405 0.134971 6.31025C0.140266 6.3158 0.145755 6.32116 0.151374 6.32646C0.156992 6.33175 0.162611 6.33698 0.168552 6.34208C0.175397 6.34796 0.182436 6.35351 0.18954 6.359C0.192963 6.36165 0.195998 6.36449 0.19955 6.36708L11.3268 14.4596L9.30613 27.5941C9.30587 27.5957 9.30568 27.5972 9.30542 27.5989L9.30516 27.6004C9.30484 27.6024 9.30484 27.6044 9.30458 27.6064C9.30264 27.6201 9.30109 27.6339 9.30032 27.6476C9.29999 27.653 9.30019 27.6583 9.30006 27.6636C9.29986 27.6739 9.29961 27.6842 9.29999 27.6944C9.30032 27.7024 9.30122 27.7102 9.30193 27.7181C9.30264 27.7256 9.30309 27.7331 9.30413 27.7405C9.30542 27.7497 9.30729 27.7588 9.3091 27.7679C9.31033 27.774 9.3113 27.7801 9.31278 27.7861C9.31498 27.7954 9.31775 27.8045 9.32047 27.8136C9.32221 27.8195 9.32382 27.8253 9.32583 27.8312C9.32873 27.8395 9.33209 27.8477 9.33545 27.856C9.33803 27.8624 9.34049 27.8689 9.34339 27.8751C9.34662 27.8822 9.35024 27.889 9.35379 27.8959C9.35753 27.9031 9.36115 27.9103 9.36522 27.9174C9.36851 27.923 9.37219 27.9285 9.37568 27.934C9.38059 27.9418 9.3855 27.9495 9.39092 27.957C9.39435 27.9617 9.39803 27.9663 9.40158 27.9708C9.40758 27.9786 9.41359 27.9863 9.42011 27.9937C9.42399 27.9981 9.42818 28.0022 9.43219 28.0065C9.43878 28.0135 9.4453 28.0205 9.45234 28.0271C9.45757 28.032 9.46319 28.0366 9.46868 28.0413C9.47487 28.0467 9.48101 28.0521 9.48753 28.0571C9.49547 28.0633 9.50387 28.0689 9.51227 28.0746C9.51685 28.0777 9.52118 28.081 9.52583 28.0839C9.53752 28.0913 9.54966 28.098 9.56206 28.1044C9.5638 28.1053 9.56535 28.1063 9.56709 28.1072C9.56729 28.1073 9.56748 28.1074 9.56768 28.1075C9.58401 28.1156 9.60087 28.1229 9.61824 28.1292C9.62257 28.1307 9.62696 28.1318 9.63129 28.1333C9.64317 28.1372 9.65518 28.1409 9.66751 28.144C9.67565 28.146 9.68379 28.1474 9.69193 28.149C9.698 28.1502 9.70387 28.1518 9.71007 28.1528C9.71214 28.1531 9.71414 28.153 9.71621 28.1532C9.73862 28.1564 9.76103 28.1585 9.78337 28.1585C9.78363 28.1585 9.78389 28.1584 9.78408 28.1584H9.78434C9.80436 28.1584 9.82405 28.1568 9.84362 28.1543C9.8475 28.1538 9.85131 28.1533 9.85518 28.1528C9.89516 28.1468 9.93377 28.1359 9.97033 28.1206C9.97388 28.1191 9.97737 28.1177 9.98085 28.1161C9.99855 28.1083 10.0158 28.0995 10.0324 28.0895C10.0354 28.0877 10.0383 28.0857 10.0412 28.0838C10.0552 28.075 10.0686 28.0655 10.0816 28.0554C10.0855 28.0525 10.0893 28.0496 10.0931 28.0465C10.1075 28.0345 10.1212 28.0217 10.1342 28.008C10.1374 28.0046 10.1405 28.0011 10.1437 27.9976C10.1567 27.9831 10.1691 27.968 10.1804 27.952C10.1807 27.9515 10.1812 27.951 10.1815 27.9506C10.1937 27.933 10.2045 27.9144 10.2144 27.8952C10.2151 27.8936 10.2162 27.8922 10.217 27.8907L13.7547 20.8152L25.4759 15.7191C25.4791 15.7177 25.4819 15.716 25.485 15.7145C25.4944 15.7102 25.5036 15.7057 25.5127 15.7008C25.5136 15.7003 25.5145 15.6999 25.5154 15.6995C25.5169 15.6987 25.5184 15.6981 25.5198 15.6973C25.5232 15.6954 25.5263 15.6932 25.5297 15.6912C25.537 15.6869 25.5442 15.6824 25.5512 15.6777C25.5559 15.6746 25.5606 15.6717 25.5651 15.6684C25.5669 15.6672 25.5685 15.6658 25.5702 15.6645C25.5755 15.6606 25.5807 15.6565 25.5858 15.6524C25.587 15.6514 25.5884 15.6508 25.5897 15.6498C25.5909 15.6487 25.592 15.6476 25.5932 15.6465C25.5977 15.6428 25.6021 15.639 25.6064 15.635C25.6106 15.6312 25.6148 15.6272 25.6189 15.6232C25.6192 15.623 25.6194 15.6228 25.6197 15.6225C25.6215 15.6208 25.6234 15.6193 25.6252 15.6175C25.6266 15.6161 25.6278 15.6147 25.6292 15.6133C25.6324 15.61 25.6356 15.6066 25.6387 15.6032C25.6427 15.5988 25.6466 15.5943 25.6504 15.5898C25.6542 15.5854 25.658 15.5812 25.6616 15.5767C25.6637 15.5741 25.6656 15.5716 25.6676 15.569C25.6692 15.5669 25.6708 15.5648 25.6724 15.5628C25.6741 15.5604 25.6756 15.558 25.6772 15.5557C25.6777 15.555 25.6782 15.5542 25.6787 15.5535C25.6825 15.5482 25.6863 15.5429 25.6898 15.5375C25.6909 15.5358 25.692 15.5341 25.6931 15.5324C25.6969 15.5264 25.7003 15.5202 25.7038 15.514C25.7071 15.5082 25.7105 15.5025 25.7135 15.4966C25.7137 15.4964 25.7138 15.4961 25.714 15.4958C25.7144 15.4949 25.7149 15.494 25.7153 15.4931C25.7188 15.4862 25.7219 15.479 25.7251 15.4718C25.7277 15.466 25.7304 15.4603 25.7328 15.4543C25.7332 15.4534 25.7336 15.4524 25.734 15.4514C25.737 15.4438 25.7394 15.436 25.742 15.4282C25.7424 15.4271 25.7428 15.426 25.7432 15.4249C25.7436 15.4235 25.7444 15.4222 25.7448 15.4208L25.7468 15.4146C25.7468 15.4144 25.7468 15.4143 25.7469 15.4142L27.922 8.52641H32.5144C32.5148 8.52641 32.5151 8.52648 32.5153 8.52648C32.5164 8.52648 32.5175 8.52628 32.5186 8.52628C32.5365 8.52615 32.5541 8.52499 32.5715 8.52299C32.5764 8.52241 32.5812 8.5215 32.586 8.52079C32.6001 8.51873 32.6139 8.51621 32.6276 8.51298C32.6326 8.51182 32.6376 8.51046 32.6426 8.50911C32.6565 8.50536 32.6701 8.50097 32.6835 8.496C32.6877 8.49445 32.692 8.49302 32.6962 8.49135C32.7135 8.48437 32.7305 8.47669 32.7468 8.46784C32.7472 8.46765 32.7476 8.46732 32.748 8.46713C32.7634 8.45867 32.7782 8.44924 32.7926 8.43917C32.7981 8.43536 32.8033 8.43129 32.8085 8.42728C32.8181 8.41999 32.8274 8.41237 32.8364 8.40442C32.8416 8.39984 32.8468 8.39532 32.8517 8.39047C32.8637 8.37898 32.875 8.36697 32.8857 8.35431C32.8869 8.35289 32.8882 8.35166 32.8894 8.35024C32.9016 8.33526 32.9126 8.3195 32.923 8.30336ZM27.5633 6.44464L25.0906 14.2751L21.3815 9.74166L27.5633 6.44464ZM2.70045 2.0289L15.3128 4.2811L11.7093 13.2899L2.70045 2.0289ZM24.1908 14.705L12.5449 13.8092L16.1283 4.85082L24.1908 14.705ZM13.7314 19.769L12.4832 14.776L23.3014 15.6082L13.7314 19.769ZM12.8869 20.3848L10.7322 24.694L11.9634 16.6911L12.8869 20.3848ZM9.2214 11.7308L1.9738 6.45975H5.00463L9.2214 11.7308ZM28.6561 6.20091L30.8268 7.55759H28.2277L28.6561 6.20091Z\"\/>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Style transfer<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI image generators can transfer the style of one image to another image style.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-aadf4af\" data-id=\"aadf4af\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db66a62 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"db66a62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 24 24\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_733_2884)\">\n<path d=\"M18.8447 10.3204L18.8269 5.14563L13.6752 5.1546L13.6776 6.55774L16.4517 6.55298L9.87433 13.1552H0V24H10.8688V14.1453L17.432 7.55731L17.4415 10.3253L18.8447 10.3204ZM9.46564 22.5967H1.40332V14.5585H9.46564V22.5967Z\" \/>\n<path d=\"M3.26172 6.64868H4.66486V8.6123H3.26172V6.64868Z\" \/>\n<path d=\"M3.26172 3.31226H4.66486V5.2757H3.26172V3.31226Z\" \/>\n<path d=\"M3.26172 0H4.66486V1.96344H3.26172V0Z\" \/>\n<path d=\"M3.26172 9.95459H4.66486V11.9182H3.26172V9.95459Z\"\/>\n<path d=\"M22.5938 6.64868H23.9969V8.6123H22.5938V6.64868Z\" \/>\n<path d=\"M22.5938 3.31226H23.9969V5.2757H22.5938V3.31226Z\" \/>\n<path d=\"M22.5938 0H23.9969V1.96344H22.5938V0Z\" \/>\n<path d=\"M22.5938 9.95459H23.9969V11.9182H22.5938V9.95459Z\" \/>\n<path d=\"M22.5938 13.2603H23.9969V15.2239H22.5938V13.2603Z\" \/>\n<path d=\"M22.5938 16.5662H23.9969V18.5298H22.5938V16.5662Z\" \/>\n<path d=\"M12.6172 0H14.5806V1.40332H12.6172V0Z\" \/>\n<path d=\"M9.28125 0H11.2449V1.40332H9.28125V0Z\" \/>\n<path d=\"M5.96875 0H7.93219V1.40332H5.96875V0Z\" \/>\n<path d=\"M15.9238 0H17.8873V1.40332H15.9238V0Z\" \/>\n<path d=\"M19.2295 0H21.1929V1.40332H19.2295V0Z\" \/>\n<path d=\"M12.1611 19.447H14.1246V20.8503H12.1611V19.447Z\" \/>\n<path d=\"M15.4668 19.447H17.4302V20.8503H15.4668V19.447Z\" \/>\n<path d=\"M18.7734 19.447H20.7371V20.8503H18.7734V19.447Z\" \/>\n<path d=\"M22.1436 19.447H23.9969V20.8503H22.1436V19.447Z\" \/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_733_2884\">\n<rect width=\"24\" height=\"24\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Super resolution<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI image generators can enhance the resolution and detail of low-resolution images.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-77b58c0\" data-id=\"77b58c0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6a85a9 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"e6a85a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 20 27\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M7.64173 2.59578C8.36681 1.70216 9.01938 0.91067 9.52693 0.24684C9.5511 0.195777 9.59944 0.170245 9.62361 0.144713C9.88947 -0.0850745 10.2762 -0.0340107 10.4937 0.24684C11.0013 0.91067 11.6538 1.70216 12.3789 2.59578C15.5692 6.50216 19.9922 11.9149 19.9922 16.4341C19.9922 19.3447 18.8804 21.9745 17.0677 23.8894C15.255 25.7788 12.7656 26.9788 10.0103 26.9788C7.25503 26.9788 4.7656 25.8043 2.95291 23.8894C1.14022 21.9745 0.0284405 19.3447 0.0284405 16.4341C0.0284405 11.9149 4.4514 6.50216 7.64173 2.59578ZM3.823 22.9447C5.41817 24.6298 7.5934 25.6766 10.0103 25.6766C12.4272 25.6766 14.6025 24.6298 16.1976 22.9702C17.7686 21.3107 18.7596 18.9873 18.7596 16.4341C18.7596 12.4 14.5058 7.19152 11.4363 3.43833C10.9287 2.80003 10.4454 2.2128 10.0103 1.6511C9.57527 2.2128 9.09188 2.80003 8.58433 3.4128C5.51484 7.16599 1.26107 12.349 1.26107 16.4085C1.26107 18.9617 2.252 21.2596 3.823 22.9447Z\" \/>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Inpainting and restoration<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>I image generators can automatically fill in missing or damaged parts of the image.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a64f206 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a64f206\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5ae24e3\" data-id=\"5ae24e3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bffb5a icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"2bffb5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 28 28\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M27.4167 0H23.9167C23.762 0 23.6136 0.0614582 23.5042 0.170854C23.3948 0.280251 23.3333 0.428624 23.3333 0.583333V1.75H4.66667V0.583333C4.66667 0.428624 4.60521 0.280251 4.49581 0.170854C4.38642 0.0614582 4.23804 0 4.08333 0L0.583333 0C0.428624 0 0.280251 0.0614582 0.170854 0.170854C0.0614582 0.280251 0 0.428624 0 0.583333L0 4.08333C0 4.23804 0.0614582 4.38642 0.170854 4.49581C0.280251 4.60521 0.428624 4.66667 0.583333 4.66667H1.75V23.3333H0.583333C0.428624 23.3333 0.280251 23.3948 0.170854 23.5042C0.0614582 23.6136 0 23.762 0 23.9167L0 27.4167C0 27.5714 0.0614582 27.7197 0.170854 27.8291C0.280251 27.9385 0.428624 28 0.583333 28H4.08333C4.23804 28 4.38642 27.9385 4.49581 27.8291C4.60521 27.7197 4.66667 27.5714 4.66667 27.4167V26.25H23.3333V27.4167C23.3333 27.5714 23.3948 27.7197 23.5042 27.8291C23.6136 27.9385 23.762 28 23.9167 28H27.4167C27.5714 28 27.7197 27.9385 27.8291 27.8291C27.9385 27.7197 28 27.5714 28 27.4167V23.9167C28 23.762 27.9385 23.6136 27.8291 23.5042C27.7197 23.3948 27.5714 23.3333 27.4167 23.3333H26.25V4.66667H27.4167C27.5714 4.66667 27.7197 4.60521 27.8291 4.49581C27.9385 4.38642 28 4.23804 28 4.08333V0.583333C28 0.428624 27.9385 0.280251 27.8291 0.170854C27.7197 0.0614582 27.5714 0 27.4167 0ZM1.16667 3.5V1.16667H3.5V3.5H1.16667ZM3.5 26.8333H1.16667V24.5H3.5V26.8333ZM23.3333 23.9167V25.0833H4.66667V23.9167C4.66667 23.762 4.60521 23.6136 4.49581 23.5042C4.38642 23.3948 4.23804 23.3333 4.08333 23.3333H2.91667V4.66667H4.08333C4.23804 4.66667 4.38642 4.60521 4.49581 4.49581C4.60521 4.38642 4.66667 4.23804 4.66667 4.08333V2.91667H23.3333V4.08333C23.3333 4.23804 23.3948 4.38642 23.5042 4.49581C23.6136 4.60521 23.762 4.66667 23.9167 4.66667H25.0833V23.3333H23.9167C23.762 23.3333 23.6136 23.3948 23.5042 23.5042C23.3948 23.6136 23.3333 23.762 23.3333 23.9167ZM26.8333 24.5V26.8333H24.5V24.5H26.8333ZM26.8333 3.5H24.5V1.16667H26.8333V3.5ZM19.25 8.16667V9.18167C19.25 9.33638 19.1885 9.48475 19.0791 9.59415C18.9697 9.70354 18.8214 9.765 18.6667 9.765C18.512 9.765 18.3636 9.70354 18.2542 9.59415C18.1448 9.48475 18.0833 9.33638 18.0833 9.18167V8.75H14.5833V19.25H16.0743C16.229 19.25 16.3774 19.3115 16.4868 19.4209C16.5962 19.5302 16.6577 19.6786 16.6577 19.8333C16.6577 19.988 16.5962 20.1364 16.4868 20.2458C16.3774 20.3552 16.229 20.4167 16.0743 20.4167H11.9257C11.771 20.4167 11.6226 20.3552 11.5132 20.2458C11.4038 20.1364 11.3423 19.988 11.3423 19.8333C11.3423 19.6786 11.4038 19.5302 11.5132 19.4209C11.6226 19.3115 11.771 19.25 11.9257 19.25H13.4167V8.75H9.91667V9.18167C9.91667 9.33638 9.85521 9.48475 9.74581 9.59415C9.63642 9.70354 9.48804 9.765 9.33333 9.765C9.17862 9.765 9.03025 9.70354 8.92085 9.59415C8.81146 9.48475 8.75 9.33638 8.75 9.18167V8.16667C8.75 8.01196 8.81146 7.86358 8.92085 7.75419C9.03025 7.64479 9.17862 7.58333 9.33333 7.58333H18.6667C18.8214 7.58333 18.9697 7.64479 19.0791 7.75419C19.1885 7.86358 19.25 8.01196 19.25 8.16667Z\" \/>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Image-to-text generation<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>Some AI image generators have the ability to generate textual descriptions or captions based on an input image.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e2a1832\" data-id=\"e2a1832\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f96a806 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"f96a806\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 30 30\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M27.6175 21.2595C27.7018 21.0507 27.6634 20.7693 27.6634 20.55C27.6634 20.0631 27.6634 19.5762 27.6634 19.0893C27.6634 17.4558 27.6634 15.822 27.6634 14.1888C27.6634 10.5576 27.6634 6.9267 27.6634 3.2958C27.6634 2.5995 27.6859 1.899 27.6634 1.203C27.6634 0.4104 26.9905 0 26.2798 0C25.8661 0 25.4527 0 25.0393 0C21.4615 0 17.8834 0 14.3059 0C12.8758 0 11.4457 0 10.0156 0C9.76868 0 9.52178 0 9.27488 0C8.50478 0 8.06738 0.6453 8.06738 1.3509V10.731V15.4122V16.2735C8.06738 16.8717 8.87888 17.1075 9.18548 16.5843C9.26768 16.4439 9.26738 16.2999 9.26738 16.1469C9.26798 13.0458 9.26858 9.945 9.26918 6.8439C9.26948 5.271 9.26978 3.6981 9.27008 2.1252C9.27008 1.8219 9.27008 1.5186 9.27008 1.215C9.27038 1.1811 9.70838 1.2 9.75188 1.2C13.0132 1.2006 16.2748 1.2012 19.5364 1.2018C21.2365 1.2021 22.9363 1.2024 24.6364 1.2027C25.1254 1.2027 25.6141 1.2027 26.1031 1.203C26.1772 1.203 26.4631 1.1511 26.4631 1.2456V9.2916V19.2135V19.9425C26.4631 19.9614 24.7708 19.9515 24.6409 19.9515C23.932 19.9515 22.8409 19.7472 22.3876 20.4435C22.1947 20.7396 22.2136 21.0651 22.2136 21.3993V22.7346V23.9775C22.2136 24.1293 22.2682 24.2013 22.1149 24.2013C21.4555 24.2013 20.7961 24.2013 20.1361 24.2013C18.6292 24.2013 17.122 24.2013 15.6151 24.2013C14.9764 24.2013 14.7718 25.1007 15.3703 25.3542C15.5266 25.4205 15.7141 25.4013 15.8806 25.4013H18.0154H23.0389C23.3419 25.4013 23.5747 25.3671 23.8021 25.1397C24.2212 24.7206 24.6409 24.3009 25.06 23.8818C25.6231 23.3187 26.1862 22.7556 26.7493 22.1925C27.0133 21.9282 27.4648 21.6159 27.6175 21.2595C27.6253 21.24 27.6085 21.2802 27.6175 21.2595ZM26.0935 21.1515C25.2001 22.0449 24.307 22.938 23.4136 23.8314C23.4136 23.3949 23.4136 22.9581 23.4136 22.5216C23.4136 22.2084 23.4136 21.8949 23.4136 21.5817C23.4136 21.5205 23.3683 21.1971 23.4136 21.1515C23.4544 21.1107 23.7445 21.1515 23.7991 21.1515H24.7234H26.0935Z\" \/>\n<path d=\"M8.47833 17.7177C5.74983 17.7177 3.28233 19.5975 2.55693 22.2282C1.82493 24.8838 3.00873 27.7689 5.38113 29.1602C7.76313 30.557 10.869 30.1491 12.819 28.1991C14.769 26.2491 15.1773 23.1432 13.7802 20.7615C12.6861 18.8961 10.6419 17.7177 8.47833 17.7177ZM8.47833 28.8C5.69103 28.8 3.40323 26.3898 3.54333 23.607C3.68343 20.8245 6.20763 18.6627 8.97783 18.942C11.5608 19.2021 13.5441 21.519 13.4136 24.1098C13.2831 26.7009 11.0712 28.8 8.47833 28.8Z\" \/>\n<path d=\"M11.3787 21.4295C10.9491 21.0875 10.5945 21.4505 10.3386 21.7712C10.0335 22.1534 9.72845 22.5359 9.42365 22.9178C8.89235 23.5835 8.36105 24.2492 7.82975 24.9149C7.43315 24.5105 7.03625 24.1061 6.63995 23.7017C6.46625 23.5247 6.29765 23.3003 6.03545 23.264C5.47925 23.1875 5.13455 23.8805 5.52635 24.2798C5.90855 24.6698 6.29135 25.0595 6.67355 25.4492L7.31705 26.1053C7.47425 26.2658 7.62875 26.4188 7.87565 26.4188C8.25785 26.4212 8.48015 26.024 8.68955 25.7615C9.09605 25.2521 9.50255 24.7427 9.90905 24.2333C10.3155 23.7239 10.7223 23.2145 11.1288 22.7048C11.4117 22.3496 11.8995 21.8447 11.3787 21.4295C11.6379 21.6362 11.1195 21.2231 11.3787 21.4295Z\" \/>\n<path d=\"M11.0042 3.76323H19.5668H24.0557C24.4646 3.76323 25.0112 3.83913 25.1534 3.32253C25.349 2.61183 24.6191 2.56323 24.1505 2.56323C20.7791 2.56323 17.4077 2.56323 14.0366 2.56323C13.199 2.56323 12.3614 2.56323 11.5235 2.56323C11.3579 2.56323 11.192 2.56323 11.0264 2.56323C10.2407 2.56323 10.2155 3.76323 11.0042 3.76323Z\" \/>\n<path d=\"M11.0042 6.38305H20.0009H21.4199C22.2899 6.38305 22.2512 5.18305 21.3971 5.18305C20.0174 5.18305 18.638 5.18305 17.258 5.18305C15.6677 5.18305 14.0771 5.18305 12.4868 5.18305C12.0449 5.18305 11.603 5.18305 11.1614 5.18305C11.0561 5.18305 10.9472 5.17645 10.8446 5.20435C10.1897 5.38495 10.3247 6.38305 11.0042 6.38305Z\" \/>\n<path d=\"M11.0042 9.00296H15.389C15.7247 9.00296 16.0751 8.94986 16.1819 8.56256C16.3127 8.08766 15.9023 7.80296 15.4853 7.80296C14.6882 7.80296 13.8914 7.80296 13.094 7.80296C12.4688 7.80296 11.8439 7.80296 11.2187 7.80296C11.0402 7.80296 10.8635 7.79006 10.7018 7.88486C10.1864 8.18696 10.4063 9.00296 11.0042 9.00296Z\" \/>\n<path d=\"M11.0038 11.6232H15.0358H17.7196C18.0952 11.6232 18.8101 11.7501 19.1359 11.4981C19.5982 11.1405 19.3087 10.4232 18.7477 10.4232C18.5794 10.4232 18.4114 10.4232 18.2428 10.4232C17.4493 10.4232 16.6561 10.4232 15.8626 10.4232C14.281 10.4232 12.6994 10.4232 11.1178 10.4232C10.9456 10.4232 10.7821 10.4361 10.6369 10.5483C10.1944 10.8903 10.4437 11.6232 11.0038 11.6232Z\" \/>\n<path d=\"M11.0041 14.2431H19.819H23.2675C23.7586 14.2431 24.082 13.6839 23.7667 13.2765C23.6149 13.0803 23.398 13.0431 23.1709 13.0431C22.7005 13.0431 22.2298 13.0431 21.7594 13.0431C18.364 13.0431 14.968 13.0431 11.572 13.0431C11.3908 13.0431 11.2096 13.0431 11.0284 13.0431C10.2418 13.0431 10.2139 14.2431 11.0041 14.2431Z\" \/>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Conditional image generation<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI image generators can generate images based on specific conditions or attributes provided as input.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-e9ccebe\" data-id=\"e9ccebe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f9bb2d icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"7f9bb2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 29 29\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<mask id=\"mask0_733_2959\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"29\" height=\"29\">\n<path d=\"M0 0H29V29H0V0Z\" fill=\"white\"\/>\n<\/mask>\n<g mask=\"url(#mask0_733_2959)\">\n<path d=\"M4.30469 0.849608V24.6953H28.1504\" stroke=\"#333333\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M0.849609 4.30469H24.6953V28.1504\" stroke=\"#333333\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/g>\n<path d=\"M4.30469 21.2968L11.1016 14.4999L17.8984 21.2968\" stroke=\"#333333\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<path d=\"M15.3496 18.7479L17.8984 16.1991L24.6953 22.996\" stroke=\"#333333\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<mask id=\"mask1_733_2959\" style=\"mask-type:luminance\" maskUnits=\"userSpaceOnUse\" x=\"0\" y=\"0\" width=\"29\" height=\"29\">\n<path d=\"M0 0H29V29H0V0Z\" fill=\"white\"\/>\n<\/mask>\n<g mask=\"url(#mask1_733_2959)\">\n<path d=\"M21.2969 10.2521C21.2969 11.6598 20.1557 12.8009 18.748 12.8009C17.3404 12.8009 16.1992 11.6598 16.1992 10.2521C16.1992 8.84439 17.3404 7.70325 18.748 7.70325C20.1557 7.70325 21.2969 8.84439 21.2969 10.2521Z\" stroke=\"#333333\" stroke-width=\"1.5\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/g>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Interactive editing<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>Advanced AI image generators offer interactive editing capabilities, allowing users to make real-time modifications<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-5a03139\" data-id=\"5a03139\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01b4664 icon-position-bottom elementor-widget elementor-widget-neuros_icon_box\" data-id=\"01b4664\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-color\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 31 31\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<g clip-path=\"url(#clip0_733_2980)\">\n<path d=\"M13.1978 12.2054H9.29259C8.95734 12.2054 8.68555 12.4772 8.68555 12.8125C8.68555 13.1477 8.95734 13.4195 9.29259 13.4195H12.5347C12.2489 14.9491 10.9039 16.1106 9.29259 16.1106C7.47394 16.1106 5.99442 14.6311 5.99442 12.8124C5.99442 10.9938 7.47394 9.51426 9.29259 9.51426C10.1735 9.51426 11.0018 9.85738 11.6247 10.4803C11.8618 10.7174 12.2462 10.7174 12.4832 10.4803C12.7203 10.2432 12.7203 9.85883 12.4832 9.62185C11.6308 8.76953 10.4978 8.30017 9.29253 8.30017C6.80442 8.30017 4.78027 10.3243 4.78027 12.8124C4.78027 15.3005 6.80442 17.3247 9.29253 17.3247C11.7806 17.3247 13.8048 15.3005 13.8048 12.8124C13.8048 12.4772 13.5331 12.2054 13.1978 12.2054Z\" \/>\n<path d=\"M28.4771 5.58485H16.3312L14.7004 0.659058C14.6181 0.410573 14.3858 0.242798 14.1241 0.242798H2.52293C1.1318 0.242798 0 1.3746 0 2.76573V22.8922C0 24.2834 1.1318 25.4152 2.52293 25.4152H14.8227L16.4619 30.3418C16.5445 30.5899 16.7764 30.7572 17.0379 30.7572H28.4771C29.8683 30.7572 31.0001 29.6254 31.0001 28.2343V8.10778C31 6.71665 29.8682 5.58485 28.4771 5.58485ZM2.52293 24.2011C1.80127 24.2011 1.21415 23.614 1.21415 22.8923V2.76573C1.21415 2.04407 1.80127 1.45694 2.52293 1.45694H13.6856L17.9657 14.3847C17.966 14.3856 17.9663 14.3864 17.9666 14.3873L21.2158 24.2011H2.52293ZM20.4315 17.1514C20.4802 17.2186 21.0868 18.0522 22.0272 19.214C21.7622 19.5625 21.4814 19.9087 21.185 20.2455L19.386 14.812H24.6803C24.3052 15.601 23.6548 16.8593 22.7614 18.1867C21.9409 17.1621 21.4252 16.4537 21.4143 16.4387C21.2175 16.1673 20.838 16.1068 20.5666 16.3036C20.2952 16.5004 20.2348 16.8799 20.4315 17.1514ZM16.1022 25.4152H20.653L17.2925 28.9925L16.1022 25.4152ZM29.7859 28.2343C29.7859 28.9559 29.1988 29.5431 28.4771 29.5431H18.4411L22.4986 25.2237L22.4984 25.2235C22.5161 25.2046 22.5329 25.1848 22.5482 25.1635C22.6623 25.0056 22.6936 24.8023 22.6324 24.6173L21.622 21.5656C22.0502 21.1172 22.4502 20.6487 22.8211 20.1751C23.6263 21.1301 24.5792 22.2002 25.5928 23.2138C25.7113 23.3323 25.8667 23.3916 26.022 23.3916C26.1773 23.3916 26.3327 23.3323 26.4512 23.2138C26.6883 22.9767 26.6883 22.5923 26.4512 22.3554C25.394 21.2982 24.3919 20.1609 23.5639 19.1687C24.8506 17.3218 25.6851 15.5659 26.0182 14.8121H27.3172C27.6524 14.8121 27.9242 14.5403 27.9242 14.205C27.9242 13.8698 27.6524 13.598 27.3172 13.598H25.609C25.608 13.598 25.6068 13.598 25.6058 13.598H23.3106V12.5053C23.3106 12.17 23.0388 11.8983 22.7036 11.8983C22.3683 11.8983 22.0965 12.17 22.0965 12.5053V13.5979H18.9841L16.733 6.799H28.477C29.1987 6.799 29.7858 7.38612 29.7858 8.10778V28.2343H29.7859Z\" \/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_733_2980\">\n<rect width=\"31\" height=\"31\" \/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Image translation<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI image generators can translate images from one domain to another, such as transforming a daytime scene<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ffd7083 elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ffd7083\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-wide\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8fef883\" data-id=\"8fef883\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-30cdac8 elementor-widget elementor-widget-image\" data-id=\"30cdac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"995\" src=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2-1024x995.jpg\" class=\"attachment-large size-large wp-image-22615\" alt=\"\" srcset=\"https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2-1024x995.jpg 1024w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2-600x583.jpg 600w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2-300x291.jpg 300w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2-768x746.jpg 768w, https:\/\/nuvaleoai.co.uk\/staging\/wp-content\/uploads\/2024\/10\/Dashboard-min-dark-2.jpg 1195w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58d8fc0 neuros-video-button-alignment-right neuros-video-button-decoration-on elementor-absolute elementor-widget elementor-widget-neuros_video_button\" data-id=\"58d8fc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=XHOmBV4js_E&quot;,&quot;_position&quot;:&quot;absolute&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"neuros_video_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros_video_button_container\">\n            <div class=\"neuros_video_button_widget\">\n                                        <div class=\"elementor-wrapper elementor-open-lightbox\">\n                                                        <div class=\"elementor-custom-embed-image-overlay\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox=\"{&quot;type&quot;:&quot;video&quot;,&quot;videoType&quot;:&quot;youtube&quot;,&quot;url&quot;:&quot;https:\\\/\\\/www.youtube-nocookie.com\\\/embed\\\/XHOmBV4js_E?feature=oembed&amp;wmode=opaque&quot;,&quot;modalOptions&quot;:{&quot;id&quot;:&quot;elementor-lightbox-58d8fc0&quot;,&quot;videoAspectRatio&quot;:&quot;169&quot;}}\">\n                                <div class=\"elementor-custom-embed-play\" role=\"button\">\n                                                                                <div class=\"icon-play-wrapper\">\n                                                <i class=\"eicon-play\" aria-hidden=\"true\"><\/i>\n                                            <\/div>\n                                                                            \n                                                                                <span class=\"neuros_button_text\">Watch video<\/span>\n                                                                                <span class=\"elementor-screen-only\">Watch video<\/span>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                                <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dcdfeac\" data-id=\"dcdfeac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d387167 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"d387167\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">features<\/span><span class=\"neuros-heading-content has_gradient_color_text\">How to work with chatbot Neuro<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91728d7 icon-position-left alignment-left v-alignment-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"91728d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 20 20\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M10 0C4.48 0 0 4.48 0 10C0 15.52 4.48 20 10 20C15.52 20 20 15.52 20 10C20 4.48 15.52 0 10 0ZM10 18C5.59 18 2 14.41 2 10C2 5.59 5.59 2 10 2C14.41 2 18 5.59 18 10C18 14.41 14.41 18 10 18ZM8 12.17L14.59 5.58001L16 7.00001L8 15L4 11L5.41 9.59001L8 12.17Z\"\/>\n<\/svg><\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Natural Language Processing (NLP)<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI chatbots use NLP algorithms to understand and interpret user input, enabling them to respond in a human-like manner and handle complex queries.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-815e8d3 icon-position-left alignment-left v-alignment-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"815e8d3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 20 20\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M10 0C4.48 0 0 4.48 0 10C0 15.52 4.48 20 10 20C15.52 20 20 15.52 20 10C20 4.48 15.52 0 10 0ZM10 18C5.59 18 2 14.41 2 10C2 5.59 5.59 2 10 2C14.41 2 18 5.59 18 10C18 14.41 14.41 18 10 18ZM8 12.17L14.59 5.58001L16 7.00001L8 15L4 11L5.41 9.59001L8 12.17Z\"\/>\n<\/svg><\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">User Intent Recognition<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI chatbots can identify the intent behind user queries, enabling them to provide relevant answers or redirect users to appropriate resources.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3d82d8 icon-position-left alignment-left v-alignment-top elementor-widget elementor-widget-neuros_icon_box\" data-id=\"e3d82d8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_icon_box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-icon-box-widget\">\n                        <div class=\"icon-box-item\">\n\n                <div class=\"icon-container background-type-none\">\n                    <span class=\"icon\"><svg viewBox=\"0 0 20 20\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<path d=\"M10 0C4.48 0 0 4.48 0 10C0 15.52 4.48 20 10 20C15.52 20 20 15.52 20 10C20 4.48 15.52 0 10 0ZM10 18C5.59 18 2 14.41 2 10C2 5.59 5.59 2 10 2C14.41 2 18 5.59 18 10C18 14.41 14.41 18 10 18ZM8 12.17L14.59 5.58001L16 7.00001L8 15L4 11L5.41 9.59001L8 12.17Z\"\/>\n<\/svg><\/span>                <\/div>\n\n                <div class=\"content-container\">\n                    <h5 class=\"icon-box-title\"><span class=\"neuros-heading-content\">Natural and Rich Responses<\/span><\/h5>\n\n                    <div class=\"icon-box-info\"><p>AI chatbots can generate responses with natural language, including text, images, links, and other multimedia elements, to provide informative and engaging interactions.<\/p><\/div>\n                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc7a0ec neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_button\" data-id=\"fc7a0ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"button-widget\">\n            <div class=\"button-container\">\n                                <a class=\"neuros-button\" href=\"#\" href=\"#\" target=\"_blank\">Generate voice                        <span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span>                    \n                    <span class=\"button-inner\"><\/span>\n                <\/a>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a17ff38 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a17ff38\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-09ea36b\" data-id=\"09ea36b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-93794a7 view_type-1 title-alignment-left neuros-navigation-border-style-gradient elementor-invisible elementor-widget elementor-widget-neuros_step_carousel\" data-id=\"93794a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_step_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-step-carousel-widget style_type-1\">\n            <h2 class=\"neuros-heading heading-with-pagination\"><span class=\"neuros-heading-inner\"><span class=\"neuros-subheading\">how it works<\/span><span class=\"neuros-heading-content\">Neural networks are a fundamental component of Artificial Intelligence (AI) systems<\/span><\/span><div class=\"owl-nav owl-nav-93794a7\"><\/div><\/h2>            \n                        <div class=\"steps-slider-container\">\n                <div class=\"steps-slider owl-carousel owl-theme\" data-slider-options=\"{&quot;items&quot;:3,&quot;nav&quot;:true,&quot;dots&quot;:false,&quot;autoplayHoverPause&quot;:true,&quot;autoplay&quot;:false,&quot;autoplaySpeed&quot;:300,&quot;autoplayTimeout&quot;:5000,&quot;loop&quot;:true,&quot;speed&quot;:500,&quot;navContainer&quot;:&quot;.owl-nav-93794a7&quot;}\">\n                    <div class=\"step-item slider-item\"><div class=\"step-number\">01<\/div><div class=\"step-content\"><h6 class=\"step-title\">Neurons and Layers<\/h6><div class=\"step-description\">A neural network consists of interconnected nodes called neurons. Neurons are organized into layers.<\/div><\/div><\/div><div class=\"step-item slider-item\"><div class=\"step-number\">02<\/div><div class=\"step-content\"><h6 class=\"step-title\">Activation Function<\/h6><div class=\"step-description\">Each neuron applies an activation function to the weighted sum of its inputs and produces an output<\/div><\/div><\/div><div class=\"step-item slider-item\"><div class=\"step-number\">03<\/div><div class=\"step-content\"><h6 class=\"step-title\">Feedforward Process<\/h6><div class=\"step-description\">The inputs are multiplied by their respective weights, summed up, and passed through the activation function.<\/div><\/div><\/div><div class=\"step-item slider-item\"><div class=\"step-number\">04<\/div><div class=\"step-content\"><h6 class=\"step-title\">Neurons and Layers<\/h6><div class=\"step-description\">A neural network consists of interconnected nodes called neurons. Neurons are organized into layers.<\/div><\/div><\/div>                <\/div>                    \n            <\/div>            \n        <\/div>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b87ac1 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"5b87ac1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d953c16\" data-id=\"d953c16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section data-parallax=\"scroll\" class=\"elementor-section elementor-inner-section elementor-element elementor-element-4fd7739 elementor-section-full_width elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"4fd7739\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-20b9a56\" data-id=\"20b9a56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02d744d elementor-widget elementor-widget-neuros_testimonial_carousel\" data-id=\"02d744d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_testimonial_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-testimonial-carousel-widget\">\n            <div class=\"testimonial-carousel-wrapper\">\n\n                <div class=\"testimonials-slider-container\">\n                    <div class=\"testimonials-slider owl-carousel owl-theme\" data-slider-options=\"{&quot;items&quot;:1,&quot;nav&quot;:true,&quot;dots&quot;:false,&quot;autoplayHoverPause&quot;:true,&quot;autoplay&quot;:false,&quot;autoplaySpeed&quot;:300,&quot;autoplayTimeout&quot;:5000,&quot;loop&quot;:true,&quot;speed&quot;:500,&quot;dotsContainer&quot;:&quot;.owl-dots-02d744d&quot;,&quot;navContainer&quot;:&quot;.owl-nav-02d744d&quot;,&quot;navText&quot;:[&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;icon-button-arrow-left\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;&lt;i aria-hidden=\\&quot;true\\&quot; class=\\&quot;icon-button-arrow\\&quot;&gt;&lt;\\\/i&gt;&quot;]}\">\n                        <div class=\"testimonial-item slider-item slider-item-type-1\"><div class=\"testimonial\"><p>Working withNeuro has been a game-changer for our business. Their AI solutions have revolutionized our operations, enabling us to automate repetitive tasks and make data-driven decisions with ease. We couldn't be happier with the results.\"<\/p><\/div><div class=\"author-container\"><div class=\"author-info\"><span class=\"author-name\">John Anderson<\/span><span class=\"author-position\">CEO of XYZ Company<\/span><\/div><\/div><\/div><div class=\"testimonial-item slider-item slider-item-type-1\"><div class=\"testimonial\"><p>Working withNeuro has been a game-changer for our business. Their AI solutions have revolutionized our operations, enabling us to automate repetitive tasks and make data-driven decisions with ease. We couldn't be happier with the results.\"<\/p><\/div><div class=\"author-container\"><div class=\"author-info\"><span class=\"author-name\">John Anderson<\/span><span class=\"author-position\">CEO of XYZ Company<\/span><\/div><\/div><\/div>                    <\/div>\n                <\/div>\n                <div class=\"owl-nav-wrapper\"><div class=\"owl-nav owl-nav-02d744d\"><\/div><\/div>            <\/div>\n        <\/div>\n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9d01417\" data-id=\"9d01417\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3d3ec5 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"b3d3ec5\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">testimonials<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Hear what our customers say about our AI solutions<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52bcc8f elementor-widget elementor-widget-counter\" data-id=\"52bcc8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"counter.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-counter\">\n\t\t\t<div class=\"elementor-counter-title\">Happy clients<\/div>\t\t\t<div class=\"elementor-counter-number-wrapper\">\n\t\t\t\t<span class=\"elementor-counter-number-prefix\"><\/span>\n\t\t\t\t<span class=\"elementor-counter-number\" data-duration=\"2000\" data-to-value=\"250\" data-from-value=\"0\" data-delimiter=\",\">0<\/span>\n\t\t\t\t<span class=\"elementor-counter-number-suffix\">+<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-62128d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"62128d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b1dc67b\" data-id=\"b1dc67b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e78aaa6 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"e78aaa6\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">pricing<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Simple and flexible.<br \/>Only pay for what you use.<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1c2c389\" data-id=\"1c2c389\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5788155 neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"5788155\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-wide\">\n                \n                                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Basic<\/div><div class=\"price-item-description\">Great for private individuals<\/div><\/div>                        <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field \">1 User<\/div>\n                                                                    <div class=\"price-item-custom-field \">Unlimited Projects<\/div>\n                                                                    <div class=\"price-item-custom-field \">Download prototypes<\/div>\n                                                                    <div class=\"price-item-custom-field \">1 Gb workspace<\/div>\n                                                        <\/div>\n                        <div class=\"price-item-price-wrapper\">                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"price\">Free<\/span>                            <\/div>\n\n                                                    <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"neuros-button\" href=\"#\" >Get started                                    <span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span><span class=\"button-inner\">                                    \n                                <\/a>\n                            <\/div>\n                        <\/div>                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6269ac5 neuros-button-border-style-solid neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_price_item\" data-id=\"6269ac5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_price_item.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"neuros-price-item-widget\">\n            <div class=\"price-item price-item-type-wide\">\n                \n                <div class=\"price-item-label-wrapper\"><div class=\"price-item-label\">Popular<\/div><\/div>                <div class=\"price-item-inner\">\n\n                    <div class=\"price-item-title-wrapper\"><div class=\"price-item-title\">Premium<\/div><div class=\"price-item-description\">14  days free period<\/div><\/div>                        <div class=\"price-item-custom-fields\">\n                                                                <div class=\"price-item-custom-field \">3 Users<\/div>\n                                                                    <div class=\"price-item-custom-field \">Unlimited Projects<\/div>\n                                                                    <div class=\"price-item-custom-field \">Download prototypes<\/div>\n                                                                    <div class=\"price-item-custom-field \">100 Gb  workspace<\/div>\n                                                        <\/div>\n                        <div class=\"price-item-price-wrapper\">                        <div class=\"price-item-container price-item-currency-position-before\">\n                            <div class=\"price-wrapper\">\n                                <span class=\"currency\">$<\/span><span class=\"price\">99<\/span>                            <\/div>\n\n                            <div class=\"price-item-period\">\/mo<\/div>                        <\/div>\n                        \n                                                <div class=\"price-item-button-container\">\n                                <a class=\"neuros-button\" href=\"#\" >Get started                                    <span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span><span class=\"button-inner\">                                    \n                                <\/a>\n                            <\/div>\n                        <\/div>                <\/div>\n            <\/div>\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ad51f38 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"ad51f38\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ef994ec\" data-id=\"ef994ec\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8e1e739 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e1e739\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-7b04143\" data-id=\"7b04143\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c565e66 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"c565e66\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-subheading\">faq<\/span><span class=\"neuros-heading-content has_gradient_color_text\">Everything you need <br \/>to know about<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9492265 elementor-accordion-style-counter elementor-widget elementor-widget-accordion\" data-id=\"9492265\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1551\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1551\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.9051447 8.7522402\"><path d=\"m 7.2060049,0.28701797 c 0.63313,-0.619103 1.69914,-0.170535 1.69914,0.71498203 v 6.75024 c 0,0.55229 -0.44771,1 -1,1 h -6.90314 c -0.89630999,0 -1.33998699,-1.08833 -0.69913999,-1.71498 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.7522402 8.9151068\"><path d=\"M 0.28599559,1.6980872 C -0.33217141,1.0640472 0.11797359,-0.00130779 1.0034886,1.2051406e-6 L 7.7537186,0.00998121 c 0.55229,8.17e-4 0.99934,0.449193 0.99852,1.00147599 l -0.0102,6.90313 c -0.00133,0.89631 -1.09031,1.33838 -1.71602,0.69661 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What is Artificial Intellegance?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1551\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1551\"><p>Machine Learning is a subset of AI that focuses on developing algorithms and models that allow computers to learn from data and improve their performance over time. It plays a crucial role in enabling AI systems to recognize patterns, make predictions, and adapt to new information.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1552\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1552\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.9051447 8.7522402\"><path d=\"m 7.2060049,0.28701797 c 0.63313,-0.619103 1.69914,-0.170535 1.69914,0.71498203 v 6.75024 c 0,0.55229 -0.44771,1 -1,1 h -6.90314 c -0.89630999,0 -1.33998699,-1.08833 -0.69913999,-1.71498 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.7522402 8.9151068\"><path d=\"M 0.28599559,1.6980872 C -0.33217141,1.0640472 0.11797359,-0.00130779 1.0034886,1.2051406e-6 L 7.7537186,0.00998121 c 0.55229,8.17e-4 0.99934,0.449193 0.99852,1.00147599 l -0.0102,6.90313 c -0.00133,0.89631 -1.09031,1.33838 -1.71602,0.69661 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">How does Machine Learning relate to Artificial Intelligence?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1552\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1552\"><p>Machine Learning is a subset of AI that focuses on developing algorithms and models that allow computers to learn from data and improve their performance over time. It plays a crucial role in enabling AI systems to recognize patterns, make predictions, and adapt to new information.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1553\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1553\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.9051447 8.7522402\"><path d=\"m 7.2060049,0.28701797 c 0.63313,-0.619103 1.69914,-0.170535 1.69914,0.71498203 v 6.75024 c 0,0.55229 -0.44771,1 -1,1 h -6.90314 c -0.89630999,0 -1.33998699,-1.08833 -0.69913999,-1.71498 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.7522402 8.9151068\"><path d=\"M 0.28599559,1.6980872 C -0.33217141,1.0640472 0.11797359,-0.00130779 1.0034886,1.2051406e-6 L 7.7537186,0.00998121 c 0.55229,8.17e-4 0.99934,0.449193 0.99852,1.00147599 l -0.0102,6.90313 c -0.00133,0.89631 -1.09031,1.33838 -1.71602,0.69661 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Is Artificial Intelligence replacing human jobs?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1553\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1553\"><p>Machine Learning is a subset of AI that focuses on developing algorithms and models that allow computers to learn from data and improve their performance over time. It plays a crucial role in enabling AI systems to recognize patterns, make predictions, and adapt to new information.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1554\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1554\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.9051447 8.7522402\"><path d=\"m 7.2060049,0.28701797 c 0.63313,-0.619103 1.69914,-0.170535 1.69914,0.71498203 v 6.75024 c 0,0.55229 -0.44771,1 -1,1 h -6.90314 c -0.89630999,0 -1.33998699,-1.08833 -0.69913999,-1.71498 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:svg=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 8.7522402 8.9151068\"><path d=\"M 0.28599559,1.6980872 C -0.33217141,1.0640472 0.11797359,-0.00130779 1.0034886,1.2051406e-6 L 7.7537186,0.00998121 c 0.55229,8.17e-4 0.99934,0.449193 0.99852,1.00147599 l -0.0102,6.90313 c -0.00133,0.89631 -1.09031,1.33838 -1.71602,0.69661 z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">What are the different types of Artificial Intelligence?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1554\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1554\"><p>Machine Learning is a subset of AI that focuses on developing algorithms and models that allow computers to learn from data and improve their performance over time. It plays a crucial role in enabling AI systems to recognize patterns, make predictions, and adapt to new information.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-174b668 neuros-button-border-style-gradient neuros-button-bakground-style-solid elementor-widget elementor-widget-neuros_button\" data-id=\"174b668\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"button-widget\">\n            <div class=\"button-container\">\n                                <a class=\"neuros-button\" href=\"https:\/\/demo.artureanec.com\/themes\/neuros-dark\/faq\/\" href=\"https:\/\/demo.artureanec.com\/themes\/neuros-dark\/faq\/\" target=\"_blank\">Explore more                        <span class=\"icon-button-arrow left\"><\/span><span class=\"icon-button-arrow right\"><\/span>                    \n                    <span class=\"button-inner\"><\/span>\n                <\/a>\n                            <\/div>\n        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4935511 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"4935511\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3f975c8\" data-id=\"3f975c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8d2a7df elementor-section-content-top elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8d2a7df\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6dadd7b\" data-id=\"6dadd7b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e041800 elementor-invisible elementor-widget elementor-widget-neuros_heading\" data-id=\"e041800\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;neuros_heading_animation&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"neuros_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"neuros-heading-widget\"><h2 class=\"neuros-heading\"><span class=\"neuros-heading-content has_gradient_color_text\">Subscribe for latest updates &amp; insights<\/span><\/h2><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c988b elementor-widget elementor-widget-text-editor\" data-id=\"d4c988b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Pacific hake false trevally queen parrotfish black prickleback mosshead warbonnet sweeper! Greenling sleeper.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68a0d0b\" data-id=\"68a0d0b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef2f4ea elementor-widget__width-initial elementor-widget-mobile__width-inherit mailchimp-button-border-style-solid mailchimp-button-bakground-style-solid elementor-widget elementor-widget-neuros_mailchimp\" data-id=\"ef2f4ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"neuros_mailchimp.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t        <div class=\"neuros-mailchimp-widget\">\n                    <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9c9c11 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"c9c9c11\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8803f6d\" data-id=\"8803f6d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f20e876 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f20e876\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1d2ea8c\" data-id=\"1d2ea8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf23b6a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bf23b6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Free 14-day trial No credit card required Icon-star-filled Icon-star-filled Icon-star-filled Icon-star-filled Icon-star-filled 20K+ users Watch video Watch video Assist in seamlessly integrating AI solutions into your existing systems and deploying them at scale. Watch video Watch video Happy clients 0 +&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-10398","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/pages\/10398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/comments?post=10398"}],"version-history":[{"count":0,"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/pages\/10398\/revisions"}],"wp:attachment":[{"href":"https:\/\/nuvaleoai.co.uk\/staging\/wp-json\/wp\/v2\/media?parent=10398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}